{"id":12307,"date":"2018-07-04T10:47:04","date_gmt":"2018-07-04T08:47:04","guid":{"rendered":"http:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg"},"modified":"2022-01-21T13:44:38","modified_gmt":"2022-01-21T12:44:38","slug":"5-18_coverstory-gyr-alliance-ringe-polieren-2","status":"inherit","type":"attachment","link":"https:\/\/www.goldor.ch\/fr\/la-plus-belle-couverture-2\/5-18_coverstory-gyr-alliance-ringe-polieren-2\/","title":{"rendered":"5-18_coverstory-gyr-alliance-ringe-polieren"},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-12307","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5-18_coverstory-gyr-alliance-ringe-polieren - Gold&#039;Or<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5-18_coverstory-gyr-alliance-ringe-polieren - Gold&#039;Or\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Gold&#039;Or\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/goldormagazin\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-21T12:44:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Goldormagazin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg\",\"url\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg\",\"name\":\"5-18_coverstory-gyr-alliance-ringe-polieren - Gold'Or\",\"isPartOf\":{\"@id\":\"https:\/\/www.goldor.ch\/#website\"},\"datePublished\":\"2018-07-04T08:47:04+00:00\",\"dateModified\":\"2022-01-21T12:44:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.goldor.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La plus belle couverture\",\"item\":\"https:\/\/www.goldor.ch\/fr\/la-plus-belle-couverture-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"5-18_coverstory-gyr-alliance-ringe-polieren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.goldor.ch\/#website\",\"url\":\"https:\/\/www.goldor.ch\/\",\"name\":\"Gold'Or\",\"description\":\"La revue professionnelle suisse de la bijouterie et de l'horlogerie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.goldor.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5-18_coverstory-gyr-alliance-ringe-polieren - Gold'Or","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg","og_locale":"fr_FR","og_type":"article","og_title":"5-18_coverstory-gyr-alliance-ringe-polieren - Gold'Or","og_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg","og_site_name":"Gold'Or","article_publisher":"https:\/\/www.facebook.com\/goldormagazin\/","article_modified_time":"2022-01-21T12:44:38+00:00","og_image":[{"width":1000,"height":1333,"url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Goldormagazin","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg","url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg","name":"5-18_coverstory-gyr-alliance-ringe-polieren - Gold'Or","isPartOf":{"@id":"https:\/\/www.goldor.ch\/#website"},"datePublished":"2018-07-04T08:47:04+00:00","dateModified":"2022-01-21T12:44:38+00:00","breadcrumb":{"@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.goldor.ch\/"},{"@type":"ListItem","position":2,"name":"La plus belle couverture","item":"https:\/\/www.goldor.ch\/fr\/la-plus-belle-couverture-2\/"},{"@type":"ListItem","position":3,"name":"5-18_coverstory-gyr-alliance-ringe-polieren"}]},{"@type":"WebSite","@id":"https:\/\/www.goldor.ch\/#website","url":"https:\/\/www.goldor.ch\/","name":"Gold'Or","description":"La revue professionnelle suisse de la bijouterie et de l'horlogerie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.goldor.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg'><img decoding=\"async\" width=\"383\" height=\"510\" src=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren-383x510.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren-383x510.jpg 383w, https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren-768x1024.jpg 768w, https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren-765x1020.jpg 765w, https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg 1000w\" sizes=\"(max-width: 383px) 100vw, 383px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<a href=\"https:\/\/www.goldor.ch\/fr\/la-plus-belle-couverture-2\/5-18_coverstory-gyr-alliance-ringe-polieren-2\/\" class=\"article-more\" title=\"mehr\">plus<\/a>"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":1333,"file":"2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg","sizes":{"thumbnail":{"file":"5-18_coverstory-gyr-alliance-ringe-polieren-300x170.jpg","width":300,"height":170,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren-300x170.jpg"},"medium":{"file":"5-18_coverstory-gyr-alliance-ringe-polieren-383x510.jpg","width":383,"height":510,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren-383x510.jpg"},"medium_large":{"file":"5-18_coverstory-gyr-alliance-ringe-polieren-768x1024.jpg","width":768,"height":1024,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren-768x1024.jpg"},"large":{"file":"5-18_coverstory-gyr-alliance-ringe-polieren-765x1020.jpg","width":765,"height":1020,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren-765x1020.jpg"},"full":{"file":"5-18_coverstory-gyr-alliance-ringe-polieren.jpg","width":1000,"height":1333,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"filesize":157083},"post":38864,"source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2018\/07\/5-18_coverstory-gyr-alliance-ringe-polieren.jpg","filename":"5-18_coverstory-gyr-alliance-ringe-polieren.jpg","filesize":157083,"_links":{"self":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/media\/12307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/comments?post=12307"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":38864,"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/posts\/38864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}