{"id":23095,"date":"2020-01-29T11:02:46","date_gmt":"2020-01-29T10:02:46","guid":{"rendered":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg"},"modified":"2022-01-21T13:45:19","modified_gmt":"2022-01-21T12:45:19","slug":"1-20_jewellery_colpo-zilio_schliesse-fu%cc%88r-ohrhaenger_cz-af_0080mod-2","status":"inherit","type":"attachment","link":"https:\/\/www.goldor.ch\/fr\/la-plus-belle-couverture-2\/1-20_jewellery_colpo-zilio_schliesse-fu%cc%88r-ohrhaenger_cz-af_0080mod-2\/","title":{"rendered":"1-20_Jewellery_Colpo-&#038;-Zilio_Schliesse-fu\u0308r-Ohrhaenger_C&#038;Z-AF_0080mod"},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-23095","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1-20_Jewellery_Colpo-&amp;-Zilio_Schliesse-fu\u0308r-Ohrhaenger_C&amp;Z-AF_0080mod - Gold&#039;Or<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1-20_Jewellery_Colpo-&amp;-Zilio_Schliesse-fu\u0308r-Ohrhaenger_C&amp;Z-AF_0080mod - Gold&#039;Or\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Gold&#039;Or\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/goldormagazin\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-21T12:45:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Goldormagazin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg\",\"url\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg\",\"name\":\"1-20_Jewellery_Colpo-&-Zilio_Schliesse-fu\u0308r-Ohrhaenger_C&Z-AF_0080mod - Gold'Or\",\"isPartOf\":{\"@id\":\"https:\/\/www.goldor.ch\/#website\"},\"datePublished\":\"2020-01-29T10:02:46+00:00\",\"dateModified\":\"2022-01-21T12:45:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.goldor.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La plus belle couverture\",\"item\":\"https:\/\/www.goldor.ch\/fr\/la-plus-belle-couverture-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1-20_Jewellery_Colpo-&#038;-Zilio_Schliesse-fu\u0308r-Ohrhaenger_C&#038;Z-AF_0080mod\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.goldor.ch\/#website\",\"url\":\"https:\/\/www.goldor.ch\/\",\"name\":\"Gold'Or\",\"description\":\"La revue professionnelle suisse de la bijouterie et de l'horlogerie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.goldor.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1-20_Jewellery_Colpo-&-Zilio_Schliesse-fu\u0308r-Ohrhaenger_C&Z-AF_0080mod - Gold'Or","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg","og_locale":"fr_FR","og_type":"article","og_title":"1-20_Jewellery_Colpo-&-Zilio_Schliesse-fu\u0308r-Ohrhaenger_C&Z-AF_0080mod - Gold'Or","og_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg","og_site_name":"Gold'Or","article_publisher":"https:\/\/www.facebook.com\/goldormagazin\/","article_modified_time":"2022-01-21T12:45:19+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Goldormagazin","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg","url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg","name":"1-20_Jewellery_Colpo-&-Zilio_Schliesse-fu\u0308r-Ohrhaenger_C&Z-AF_0080mod - Gold'Or","isPartOf":{"@id":"https:\/\/www.goldor.ch\/#website"},"datePublished":"2020-01-29T10:02:46+00:00","dateModified":"2022-01-21T12:45:19+00:00","breadcrumb":{"@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.goldor.ch\/"},{"@type":"ListItem","position":2,"name":"La plus belle couverture","item":"https:\/\/www.goldor.ch\/fr\/la-plus-belle-couverture-2\/"},{"@type":"ListItem","position":3,"name":"1-20_Jewellery_Colpo-&#038;-Zilio_Schliesse-fu\u0308r-Ohrhaenger_C&#038;Z-AF_0080mod"}]},{"@type":"WebSite","@id":"https:\/\/www.goldor.ch\/#website","url":"https:\/\/www.goldor.ch\/","name":"Gold'Or","description":"La revue professionnelle suisse de la bijouterie et de l'horlogerie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.goldor.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg'><img decoding=\"async\" width=\"680\" height=\"510\" src=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod-680x510.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod-680x510.jpg 680w, https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod-768x576.jpg 768w, https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg 1000w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<a href=\"https:\/\/www.goldor.ch\/fr\/la-plus-belle-couverture-2\/1-20_jewellery_colpo-zilio_schliesse-fu%cc%88r-ohrhaenger_cz-af_0080mod-2\/\" class=\"article-more\" title=\"mehr\">plus<\/a>"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":750,"file":"2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg","sizes":{"thumbnail":{"file":"1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod-300x170.jpg","width":300,"height":170,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod-300x170.jpg"},"medium":{"file":"1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod-680x510.jpg","width":680,"height":510,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod-680x510.jpg"},"medium_large":{"file":"1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod-768x576.jpg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod-768x576.jpg"},"full":{"file":"1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg","width":1000,"height":750,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":38864,"source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg","filename":"1-20_Jewellery_Colpo-Zilio_Schliesse-fu\u0308r-Ohrhaenger_CZ-AF_0080mod.jpg","filesize":null,"_links":{"self":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/media\/23095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/comments?post=23095"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":38864,"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/posts\/38864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}