{"id":23099,"date":"2020-01-29T11:02:51","date_gmt":"2020-01-29T10:02:51","guid":{"rendered":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg"},"modified":"2022-01-21T13:45:19","modified_gmt":"2022-01-21T12:45:19","slug":"1-20_jewellery-colpo-zilio_kundespezifik_001b-copia_kundespezifik-2","status":"inherit","type":"attachment","link":"https:\/\/www.goldor.ch\/fr\/la-plus-belle-couverture-2\/1-20_jewellery-colpo-zilio_kundespezifik_001b-copia_kundespezifik-2\/","title":{"rendered":"1-20_Jewellery-Colpo-&#038;-Zilio_Kundespezifik_001b-copia_Kundespezifik"},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-23099","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1-20_Jewellery-Colpo-&amp;-Zilio_Kundespezifik_001b-copia_Kundespezifik - Gold&#039;Or<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1-20_Jewellery-Colpo-&amp;-Zilio_Kundespezifik_001b-copia_Kundespezifik - Gold&#039;Or\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Gold&#039;Or\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/goldormagazin\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-21T12:45:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"707\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Goldormagazin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg\",\"url\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg\",\"name\":\"1-20_Jewellery-Colpo-&-Zilio_Kundespezifik_001b-copia_Kundespezifik - Gold'Or\",\"isPartOf\":{\"@id\":\"https:\/\/www.goldor.ch\/#website\"},\"datePublished\":\"2020-01-29T10:02:51+00:00\",\"dateModified\":\"2022-01-21T12:45:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.goldor.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La plus belle couverture\",\"item\":\"https:\/\/www.goldor.ch\/fr\/la-plus-belle-couverture-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1-20_Jewellery-Colpo-&#038;-Zilio_Kundespezifik_001b-copia_Kundespezifik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.goldor.ch\/#website\",\"url\":\"https:\/\/www.goldor.ch\/\",\"name\":\"Gold'Or\",\"description\":\"La revue professionnelle suisse de la bijouterie et de l'horlogerie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.goldor.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1-20_Jewellery-Colpo-&-Zilio_Kundespezifik_001b-copia_Kundespezifik - Gold'Or","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg","og_locale":"fr_FR","og_type":"article","og_title":"1-20_Jewellery-Colpo-&-Zilio_Kundespezifik_001b-copia_Kundespezifik - Gold'Or","og_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg","og_site_name":"Gold'Or","article_publisher":"https:\/\/www.facebook.com\/goldormagazin\/","article_modified_time":"2022-01-21T12:45:19+00:00","og_image":[{"width":707,"height":1000,"url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Goldormagazin","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg","url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg","name":"1-20_Jewellery-Colpo-&-Zilio_Kundespezifik_001b-copia_Kundespezifik - Gold'Or","isPartOf":{"@id":"https:\/\/www.goldor.ch\/#website"},"datePublished":"2020-01-29T10:02:51+00:00","dateModified":"2022-01-21T12:45:19+00:00","breadcrumb":{"@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.goldor.ch\/"},{"@type":"ListItem","position":2,"name":"La plus belle couverture","item":"https:\/\/www.goldor.ch\/fr\/la-plus-belle-couverture-2\/"},{"@type":"ListItem","position":3,"name":"1-20_Jewellery-Colpo-&#038;-Zilio_Kundespezifik_001b-copia_Kundespezifik"}]},{"@type":"WebSite","@id":"https:\/\/www.goldor.ch\/#website","url":"https:\/\/www.goldor.ch\/","name":"Gold'Or","description":"La revue professionnelle suisse de la bijouterie et de l'horlogerie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.goldor.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg'><img decoding=\"async\" width=\"361\" height=\"510\" src=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik-361x510.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik-361x510.jpg 361w, https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg 707w\" sizes=\"(max-width: 361px) 100vw, 361px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<a href=\"https:\/\/www.goldor.ch\/fr\/la-plus-belle-couverture-2\/1-20_jewellery-colpo-zilio_kundespezifik_001b-copia_kundespezifik-2\/\" class=\"article-more\" title=\"mehr\">plus<\/a>"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":707,"height":1000,"file":"2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg","sizes":{"thumbnail":{"file":"1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik-300x170.jpg","width":300,"height":170,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik-300x170.jpg"},"medium":{"file":"1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik-361x510.jpg","width":361,"height":510,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik-361x510.jpg"},"full":{"file":"1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg","width":707,"height":1000,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"filesize":21007},"post":38864,"source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/01\/1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg","filename":"1-20_Jewellery-Colpo-Zilio_Kundespezifik_001b-copia_Kundespezifik.jpg","filesize":21007,"_links":{"self":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/media\/23099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/comments?post=23099"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":38864,"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/posts\/38864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}