{"id":28869,"date":"2020-10-01T11:16:59","date_gmt":"2020-10-01T09:16:59","guid":{"rendered":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg"},"modified":"2022-01-21T13:45:31","modified_gmt":"2022-01-21T12:45:31","slug":"7-2020_stones_edelsteinlexikon_geigerzaehler-2","status":"inherit","type":"attachment","link":"https:\/\/www.goldor.ch\/fr\/la-plus-belle-couverture-2\/7-2020_stones_edelsteinlexikon_geigerzaehler-2\/","title":{"rendered":"7-2020_Stones_Edelsteinlexikon_Geigerzaehler"},"author":1975,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-28869","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>7-2020_Stones_Edelsteinlexikon_Geigerzaehler - Gold&#039;Or<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7-2020_Stones_Edelsteinlexikon_Geigerzaehler - Gold&#039;Or\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Gold&#039;Or\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/goldormagazin\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-21T12:45:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1776\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Goldormagazin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg\",\"url\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg\",\"name\":\"7-2020_Stones_Edelsteinlexikon_Geigerzaehler - Gold'Or\",\"isPartOf\":{\"@id\":\"https:\/\/www.goldor.ch\/#website\"},\"datePublished\":\"2020-10-01T09:16:59+00:00\",\"dateModified\":\"2022-01-21T12:45:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.goldor.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La plus belle couverture\",\"item\":\"https:\/\/www.goldor.ch\/fr\/la-plus-belle-couverture-2\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"7-2020_Stones_Edelsteinlexikon_Geigerzaehler\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.goldor.ch\/#website\",\"url\":\"https:\/\/www.goldor.ch\/\",\"name\":\"Gold'Or\",\"description\":\"La revue professionnelle suisse de la bijouterie et de l'horlogerie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.goldor.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"7-2020_Stones_Edelsteinlexikon_Geigerzaehler - Gold'Or","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg","og_locale":"fr_FR","og_type":"article","og_title":"7-2020_Stones_Edelsteinlexikon_Geigerzaehler - Gold'Or","og_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg","og_site_name":"Gold'Or","article_publisher":"https:\/\/www.facebook.com\/goldormagazin\/","article_modified_time":"2022-01-21T12:45:31+00:00","og_image":[{"width":1000,"height":1776,"url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Goldormagazin","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg","url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg","name":"7-2020_Stones_Edelsteinlexikon_Geigerzaehler - Gold'Or","isPartOf":{"@id":"https:\/\/www.goldor.ch\/#website"},"datePublished":"2020-10-01T09:16:59+00:00","dateModified":"2022-01-21T12:45:31+00:00","breadcrumb":{"@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.goldor.ch\/"},{"@type":"ListItem","position":2,"name":"La plus belle couverture","item":"https:\/\/www.goldor.ch\/fr\/la-plus-belle-couverture-2\/"},{"@type":"ListItem","position":3,"name":"7-2020_Stones_Edelsteinlexikon_Geigerzaehler"}]},{"@type":"WebSite","@id":"https:\/\/www.goldor.ch\/#website","url":"https:\/\/www.goldor.ch\/","name":"Gold'Or","description":"La revue professionnelle suisse de la bijouterie et de l'horlogerie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.goldor.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg'><img decoding=\"async\" width=\"287\" height=\"510\" src=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler-287x510.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler-287x510.jpg 287w, https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler-574x1020.jpg 574w, https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler-768x1364.jpg 768w, https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler-865x1536.jpg 865w, https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg 1000w\" sizes=\"(max-width: 287px) 100vw, 287px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<a href=\"https:\/\/www.goldor.ch\/fr\/la-plus-belle-couverture-2\/7-2020_stones_edelsteinlexikon_geigerzaehler-2\/\" class=\"article-more\" title=\"mehr\">plus<\/a>"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":1776,"file":"2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg","sizes":{"medium":{"file":"7-2020_Stones_Edelsteinlexikon_Geigerzaehler-287x510.jpg","width":287,"height":510,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler-287x510.jpg"},"large":{"file":"7-2020_Stones_Edelsteinlexikon_Geigerzaehler-574x1020.jpg","width":574,"height":1020,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler-574x1020.jpg"},"thumbnail":{"file":"7-2020_Stones_Edelsteinlexikon_Geigerzaehler-300x170.jpg","width":300,"height":170,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler-300x170.jpg"},"medium_large":{"file":"7-2020_Stones_Edelsteinlexikon_Geigerzaehler-768x1364.jpg","width":768,"height":1364,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler-768x1364.jpg"},"1536x1536":{"file":"7-2020_Stones_Edelsteinlexikon_Geigerzaehler-865x1536.jpg","width":865,"height":1536,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler-865x1536.jpg"},"full":{"file":"7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg","width":1000,"height":1776,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":38864,"source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2020\/10\/7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg","filename":"7-2020_Stones_Edelsteinlexikon_Geigerzaehler.jpg","filesize":220693,"_links":{"self":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/media\/28869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/users\/1975"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/comments?post=28869"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":38864,"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/posts\/38864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}