{"id":40930,"date":"2022-03-18T09:16:18","date_gmt":"2022-03-18T08:16:18","guid":{"rendered":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg"},"modified":"2022-03-18T09:16:18","modified_gmt":"2022-03-18T08:16:18","slug":"2-2022_stones_buch-wild_106-2","status":"inherit","type":"attachment","link":"https:\/\/www.goldor.ch\/fr\/2-2022_stones_buch-wild_106-2\/","title":{"rendered":"2-2022_Stones_Buch-Wild_106"},"author":1975,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-40930","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2-2022_Stones_Buch-Wild_106 - Gold&#039;Or<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2-2022_Stones_Buch-Wild_106 - Gold&#039;Or\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Gold&#039;Or\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/goldormagazin\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"679\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Goldormagazin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg\",\"url\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg\",\"name\":\"2-2022_Stones_Buch-Wild_106 - Gold'Or\",\"isPartOf\":{\"@id\":\"https:\/\/www.goldor.ch\/#website\"},\"datePublished\":\"2022-03-18T08:16:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.goldor.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2-2022_Stones_Buch-Wild_106\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.goldor.ch\/#website\",\"url\":\"https:\/\/www.goldor.ch\/\",\"name\":\"Gold'Or\",\"description\":\"La revue professionnelle suisse de la bijouterie et de l'horlogerie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.goldor.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2-2022_Stones_Buch-Wild_106 - Gold'Or","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg","og_locale":"fr_FR","og_type":"article","og_title":"2-2022_Stones_Buch-Wild_106 - Gold'Or","og_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg","og_site_name":"Gold'Or","article_publisher":"https:\/\/www.facebook.com\/goldormagazin\/","og_image":[{"width":1000,"height":679,"url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Goldormagazin","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg","url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg","name":"2-2022_Stones_Buch-Wild_106 - Gold'Or","isPartOf":{"@id":"https:\/\/www.goldor.ch\/#website"},"datePublished":"2022-03-18T08:16:18+00:00","breadcrumb":{"@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.goldor.ch\/"},{"@type":"ListItem","position":2,"name":"2-2022_Stones_Buch-Wild_106"}]},{"@type":"WebSite","@id":"https:\/\/www.goldor.ch\/#website","url":"https:\/\/www.goldor.ch\/","name":"Gold'Or","description":"La revue professionnelle suisse de la bijouterie et de l'horlogerie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.goldor.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg'><img decoding=\"async\" width=\"751\" height=\"510\" src=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106-751x510.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106-751x510.jpg 751w, https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106-768x521.jpg 768w, https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg 1000w\" sizes=\"(max-width: 751px) 100vw, 751px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<a href=\"https:\/\/www.goldor.ch\/fr\/2-2022_stones_buch-wild_106-2\/\" class=\"article-more\" title=\"mehr\">plus<\/a>"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":679,"file":"2022\/03\/2-2022_Stones_Buch-Wild_106.jpg","sizes":{"medium":{"file":"2-2022_Stones_Buch-Wild_106-751x510.jpg","width":751,"height":510,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106-751x510.jpg"},"thumbnail":{"file":"2-2022_Stones_Buch-Wild_106-300x170.jpg","width":300,"height":170,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106-300x170.jpg"},"medium_large":{"file":"2-2022_Stones_Buch-Wild_106-768x521.jpg","width":768,"height":521,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106-768x521.jpg"},"full":{"file":"2-2022_Stones_Buch-Wild_106.jpg","width":1000,"height":679,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2022\/03\/2-2022_Stones_Buch-Wild_106.jpg","filename":"2-2022_Stones_Buch-Wild_106.jpg","filesize":448350,"_links":{"self":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/media\/40930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/users\/1975"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/comments?post=40930"}]}}