{"id":59291,"date":"2024-04-30T11:49:56","date_gmt":"2024-04-30T09:49:56","guid":{"rendered":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg"},"modified":"2024-04-30T11:50:52","modified_gmt":"2024-04-30T09:50:52","slug":"3-2024-special_schaetze-gs-corina_mandaringranat-u-tsavolith-2","status":"inherit","type":"attachment","link":"https:\/\/www.goldor.ch\/fr\/3-2024-special_schaetze-gs-corina_mandaringranat-u-tsavolith-2\/","title":{"rendered":"3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith"},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-59291","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith - Gold&#039;Or<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith - Gold&#039;Or\" \/>\n<meta property=\"og:description\" content=\"Anh\u00e4nger mit einem Mandaringranat und einem Tsavolithen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Gold&#039;Or\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/goldormagazin\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-30T09:50:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"943\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Goldormagazin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg\",\"url\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg\",\"name\":\"3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith - Gold'Or\",\"isPartOf\":{\"@id\":\"https:\/\/www.goldor.ch\/#website\"},\"datePublished\":\"2024-04-30T09:49:56+00:00\",\"dateModified\":\"2024-04-30T09:50:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.goldor.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.goldor.ch\/#website\",\"url\":\"https:\/\/www.goldor.ch\/\",\"name\":\"Gold'Or\",\"description\":\"La revue professionnelle suisse de la bijouterie et de l'horlogerie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.goldor.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith - Gold'Or","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg","og_locale":"fr_FR","og_type":"article","og_title":"3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith - Gold'Or","og_description":"Anh\u00e4nger mit einem Mandaringranat und einem Tsavolithen.","og_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg","og_site_name":"Gold'Or","article_publisher":"https:\/\/www.facebook.com\/goldormagazin\/","article_modified_time":"2024-04-30T09:50:52+00:00","og_image":[{"width":1000,"height":943,"url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Goldormagazin","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg","url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg","name":"3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith - Gold'Or","isPartOf":{"@id":"https:\/\/www.goldor.ch\/#website"},"datePublished":"2024-04-30T09:49:56+00:00","dateModified":"2024-04-30T09:50:52+00:00","breadcrumb":{"@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.goldor.ch\/"},{"@type":"ListItem","position":2,"name":"3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith"}]},{"@type":"WebSite","@id":"https:\/\/www.goldor.ch\/#website","url":"https:\/\/www.goldor.ch\/","name":"Gold'Or","description":"La revue professionnelle suisse de la bijouterie et de l'horlogerie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.goldor.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg'><img decoding=\"async\" width=\"541\" height=\"510\" src=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith-541x510.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith-541x510.jpg 541w, https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith-768x724.jpg 768w, https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg 1000w\" sizes=\"(max-width: 541px) 100vw, 541px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Anh\u00e4nger mit einem Mandaringranat und einem Tsavolithen.<\/p>\n<a href=\"https:\/\/www.goldor.ch\/fr\/3-2024-special_schaetze-gs-corina_mandaringranat-u-tsavolith-2\/\" class=\"article-more\" title=\"mehr\">plus<\/a>"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1000,"height":943,"file":"2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg","filesize":107532,"sizes":{"medium":{"file":"3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith-541x510.jpg","width":541,"height":510,"filesize":50944,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith-541x510.jpg"},"thumbnail":{"file":"3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith-300x170.jpg","width":300,"height":170,"filesize":12930,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith-300x170.jpg"},"medium_large":{"file":"3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith-768x724.jpg","width":768,"height":724,"filesize":90518,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith-768x724.jpg"},"full":{"file":"3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg","width":1000,"height":943,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2024\/04\/3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg","filename":"3-2024-Special_Schaetze-GS-Corina_Mandaringranat-u-Tsavolith.jpg","filesize":107532,"_links":{"self":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/media\/59291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/comments?post=59291"}]}}