{"id":71042,"date":"2025-08-22T15:41:46","date_gmt":"2025-08-22T13:41:46","guid":{"rendered":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg"},"modified":"2025-09-04T09:45:57","modified_gmt":"2025-09-04T07:45:57","slug":"gn25_maximilian-przybylka_klein-2","status":"inherit","type":"attachment","link":"https:\/\/www.goldor.ch\/fr\/gn25_maximilian-przybylka_klein-2\/","title":{"rendered":"GN25_Maximilian-Przybylka_klein"},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-71042","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GN25_Maximilian-Przybylka_klein - Gold&#039;Or<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GN25_Maximilian-Przybylka_klein - Gold&#039;Or\" \/>\n<meta property=\"og:description\" content=\"Maximilian Przybylka\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Gold&#039;Or\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/goldormagazin\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-04T07:45:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Goldormagazin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg\",\"url\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg\",\"name\":\"GN25_Maximilian-Przybylka_klein - Gold'Or\",\"isPartOf\":{\"@id\":\"https:\/\/www.goldor.ch\/#website\"},\"datePublished\":\"2025-08-22T13:41:46+00:00\",\"dateModified\":\"2025-09-04T07:45:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.goldor.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GN25_Maximilian-Przybylka_klein\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.goldor.ch\/#website\",\"url\":\"https:\/\/www.goldor.ch\/\",\"name\":\"Gold'Or\",\"description\":\"La revue professionnelle suisse de la bijouterie et de l'horlogerie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.goldor.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GN25_Maximilian-Przybylka_klein - Gold'Or","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg","og_locale":"fr_FR","og_type":"article","og_title":"GN25_Maximilian-Przybylka_klein - Gold'Or","og_description":"Maximilian Przybylka","og_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg","og_site_name":"Gold'Or","article_publisher":"https:\/\/www.facebook.com\/goldormagazin\/","article_modified_time":"2025-09-04T07:45:57+00:00","og_image":[{"width":700,"height":512,"url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@Goldormagazin","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg","url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg","name":"GN25_Maximilian-Przybylka_klein - Gold'Or","isPartOf":{"@id":"https:\/\/www.goldor.ch\/#website"},"datePublished":"2025-08-22T13:41:46+00:00","dateModified":"2025-09-04T07:45:57+00:00","breadcrumb":{"@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.goldor.ch\/"},{"@type":"ListItem","position":2,"name":"GN25_Maximilian-Przybylka_klein"}]},{"@type":"WebSite","@id":"https:\/\/www.goldor.ch\/#website","url":"https:\/\/www.goldor.ch\/","name":"Gold'Or","description":"La revue professionnelle suisse de la bijouterie et de l'horlogerie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.goldor.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg'><img decoding=\"async\" width=\"697\" height=\"510\" src=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein-697x510.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein-697x510.jpg 697w, https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg 700w\" sizes=\"(max-width: 697px) 100vw, 697px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Maximilian Przybylka<\/p>\n<a href=\"https:\/\/www.goldor.ch\/fr\/gn25_maximilian-przybylka_klein-2\/\" class=\"article-more\" title=\"mehr\">plus<\/a>"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":700,"height":512,"file":"2025\/08\/GN25_Maximilian-Przybylka_klein.jpg","filesize":101667,"sizes":{"medium":{"file":"GN25_Maximilian-Przybylka_klein-697x510.jpg","width":697,"height":510,"filesize":65436,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein-697x510.jpg"},"thumbnail":{"file":"GN25_Maximilian-Przybylka_klein-300x170.jpg","width":300,"height":170,"filesize":12133,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein-300x170.jpg"},"full":{"file":"GN25_Maximilian-Przybylka_klein.jpg","width":700,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.goldor.ch\/wp-content\/uploads\/2025\/08\/GN25_Maximilian-Przybylka_klein.jpg","filename":"GN25_Maximilian-Przybylka_klein.jpg","filesize":101667,"_links":{"self":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/media\/71042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/comments?post=71042"}]}}