{"id":833,"count":2,"description":"","link":"https:\/\/www.goldor.ch\/fr\/tag\/goldschmied-in-efz-fr\/","name":"Goldschmied\/in EFZ","slug":"goldschmied-in-efz-fr","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Goldschmied\/in EFZ Archive - Gold&#039;Or<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.goldor.ch\/fr\/tag\/goldschmied-in-efz-fr\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Goldschmied\/in EFZ Archive - Gold&#039;Or\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.goldor.ch\/fr\/tag\/goldschmied-in-efz-fr\/\" \/>\n<meta property=\"og:site_name\" content=\"Gold&#039;Or\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Goldormagazin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.goldor.ch\/fr\/tag\/goldschmied-in-efz-fr\/\",\"url\":\"https:\/\/www.goldor.ch\/fr\/tag\/goldschmied-in-efz-fr\/\",\"name\":\"Goldschmied\/in EFZ Archive - Gold'Or\",\"isPartOf\":{\"@id\":\"https:\/\/www.goldor.ch\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.goldor.ch\/fr\/tag\/goldschmied-in-efz-fr\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.goldor.ch\/fr\/tag\/goldschmied-in-efz-fr\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.goldor.ch\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Goldschmied\/in EFZ\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.goldor.ch\/#website\",\"url\":\"https:\/\/www.goldor.ch\/\",\"name\":\"Gold'Or\",\"description\":\"La revue professionnelle suisse de la bijouterie et de l'horlogerie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.goldor.ch\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Goldschmied\/in EFZ Archive - Gold'Or","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.goldor.ch\/fr\/tag\/goldschmied-in-efz-fr\/","og_locale":"fr_FR","og_type":"article","og_title":"Goldschmied\/in EFZ Archive - Gold'Or","og_url":"https:\/\/www.goldor.ch\/fr\/tag\/goldschmied-in-efz-fr\/","og_site_name":"Gold'Or","twitter_card":"summary_large_image","twitter_site":"@Goldormagazin","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.goldor.ch\/fr\/tag\/goldschmied-in-efz-fr\/","url":"https:\/\/www.goldor.ch\/fr\/tag\/goldschmied-in-efz-fr\/","name":"Goldschmied\/in EFZ Archive - Gold'Or","isPartOf":{"@id":"https:\/\/www.goldor.ch\/#website"},"breadcrumb":{"@id":"https:\/\/www.goldor.ch\/fr\/tag\/goldschmied-in-efz-fr\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.goldor.ch\/fr\/tag\/goldschmied-in-efz-fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.goldor.ch\/"},{"@type":"ListItem","position":2,"name":"Goldschmied\/in EFZ"}]},{"@type":"WebSite","@id":"https:\/\/www.goldor.ch\/#website","url":"https:\/\/www.goldor.ch\/","name":"Gold'Or","description":"La revue professionnelle suisse de la bijouterie et de l'horlogerie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.goldor.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/tags\/833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/posts?tags=833"},{"href":"https:\/\/www.goldor.ch\/fr\/wp-json\/wp\/v2\/vsgu-news?tags=833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}